{"id":21711,"date":"2020-09-07T14:48:33","date_gmt":"2020-09-07T17:48:33","guid":{"rendered":"https:\/\/blogs.correio24horas.com.br\/mesalte\/?p=21711"},"modified":"2020-09-07T17:55:13","modified_gmt":"2020-09-07T20:55:13","slug":"revista-periodicus-busca-novos-textos-para-publicacao-sobre-intersexualidade-desafios-de-genero-veja-com-o-participar","status":"publish","type":"post","link":"https:\/\/blogs.correio24horas.com.br\/mesalte\/revista-periodicus-busca-novos-textos-para-publicacao-sobre-intersexualidade-desafios-de-genero-veja-com-o-participar\/","title":{"rendered":"&#8216;Intersexualidade: desafios de g\u00eanero&#8217;: Revista Peri\u00f3dicus busca novos textos para publica\u00e7\u00e3o. Veja com o participar"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">A Revista Peri\u00f3dicus lan\u00e7a chamada de textos para o dossi\u00ea intitulado Intersexualidade: desafios de g\u00eanero. O objetivo \u00e9 reunir trabalhos de diversas \u00e1reas do conhecimento para tratar sobre o tema. Todas as propostas devem ser enviadas atrav\u00e9s do site da revista ( <a href=\"https:\/\/portalseer.ufba.br\/index.php\/revistaperiodicus\"><a href=\"https:\/\/portalseer.ufba.br\/index.php\/revistaperiodicus\">https:\/\/portalseer.ufba.br\/index.php\/revistaperiodicus<\/a><\/a>) at\u00e9 o dia 7 de janeiro de 2021. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No site tamb\u00e9m constam informa\u00e7\u00f5es sobre a linha editorial da revista e as demais diretrizes para as pessoas autoras. O dossi\u00ea, primeiro sobre o tema a ser publicado em uma revista brasileira, ser\u00e1 organizado por Amiel Modesto Vieira, Anacely Costa, Barbara Pires e Marina Cortez. A previs\u00e3o \u00e9 que o dossi\u00ea seja publicado em maio de 2021, na d\u00e9cima quinta edi\u00e7\u00e3o da revista.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A Peri\u00f3dicus \u00e9 uma publica\u00e7\u00e3o semestral do N\u00facleo de Pesquisa e Extens\u00e3o em Culturas, G\u00eaneros e Sexualidades (NuCuS), vinculado ao Instituto de Humanidades, Artes e Ci\u00eancias Professor Milton Santos e ao Programa Multidisciplinar de P\u00f3s-gradua\u00e7\u00e3o em Cultura e Sociedade, da Universidade Federal da Bahia. A revista \u00e9 editada pelos pesquisadores Leandro Colling, Helder Thiago Maia e Matheus Ara\u00fajo dos Santos, integrantes do NuCuS.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Revista Peri\u00f3dicus lan\u00e7a chamada de textos para o dossi\u00ea intitulado Intersexualidade: desafios de g\u00eanero. O objetivo \u00e9 reunir trabalhos de diversas \u00e1reas do conhecimento para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[80,9],"tags":[1854],"class_list":["post-21711","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-home","category-me-orgulho","tag-intersexo"],"_links":{"self":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts\/21711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/comments?post=21711"}],"version-history":[{"count":2,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts\/21711\/revisions"}],"predecessor-version":[{"id":21721,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts\/21711\/revisions\/21721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/media\/21712"}],"wp:attachment":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/media?parent=21711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/categories?post=21711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/tags?post=21711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}