{"id":14662,"date":"2018-02-27T07:33:29","date_gmt":"2018-02-27T10:33:29","guid":{"rendered":"http:\/\/blogs.correio24horas.com.br\/mesalte\/?p=14662"},"modified":"2018-02-27T07:33:54","modified_gmt":"2018-02-27T10:33:54","slug":"vetada-no-volei-feminino-mulher-trans-e-obrigada-a-jogar-contra-homens","status":"publish","type":"post","link":"https:\/\/blogs.correio24horas.com.br\/mesalte\/vetada-no-volei-feminino-mulher-trans-e-obrigada-a-jogar-contra-homens\/","title":{"rendered":"Vetada no v\u00f4lei feminino, mulher trans \u00e9 obrigada a jogar contra homens"},"content":{"rendered":"<p>A jogadora de v\u00f4lei de praia\u00a0Carol Lissarassa &#8211; que fez parceria com a campe\u00e3 Juliana em um torneio de v\u00f4lei de praia em novembro de 2017 &#8211; foi vetada no \u00faltimo final de semana para disputar\u00a0a etapa de v\u00f4lei de praia de Cruz Alta do Circuito Ver\u00e3o Sesc de Esportes. Transexual, Carol foi obrigada a atuar no masculino ao lado de Helio Lucena.<\/p>\n<p>De acordo com o portal Globo Esporte, no ano passado, a atleta foi vice-campe\u00e3 da etapa de Iju\u00ed nessa mesma competi\u00e7\u00e3o, s\u00f3 que atuando no feminino. Em 2018, contudo, se inscreveu para jogar ao lado de Grazielle Gon\u00e7alves. S\u00f3 que teve sua documenta\u00e7\u00e3o vetada.<\/p>\n<p>&#8220;Fiquei indignada com a organiza\u00e7\u00e3o, porque no ano passado disputei uma etapa do Circuito Sesc e fui vice-campe\u00e3. O documento que apresentei \u00e9 o mesmo que usei em todas as competi\u00e7\u00f5es femininas que disputei at\u00e9 hoje, que \u00e9 minha identidade social como Carolinna Lissarassa, vinculada ao mesmo n\u00famero de RG do meu nome de batismo. Sempre joguei com esse documento e nunca tive resist\u00eancia. Para mim, foi um ato de discrimina\u00e7\u00e3o. Ano passado joguei e fui para o p\u00f3dio. Esse ano, ap\u00f3s todas as mat\u00e9rias que sa\u00edram, acho que estou sendo perseguida&#8221;, afirmou Carol ao Globo Esporte.<\/p>\n<p>A atleta explica que a organiza\u00e7\u00e3o do evento afirmou que\u00a0ela\u00a0teria que atuar no masculino se quisesse participar. &#8220;Joguei no masculino para combater essa discrimina\u00e7\u00e3o e para mostrar que, independentemente de masculino ou feminino, tenho talento e n\u00e3o vou parar. Se esse ato de me proibir no feminino foi uma maneira de me fazer n\u00e3o jogar, eles n\u00e3o conseguiram. Perdemos dois jogos apenas. Na semi, perdemos para os campe\u00f5es da etapa em um jogo parelho&#8221;, destacou a atleta que relatou\u00a0\u00a0dificuldades de atuar no masculino, pois sua for\u00e7a, seu impulso e sua agilidade n\u00e3o s\u00e3o as mesmas dos homens.<\/p>\n<p>Carol est\u00e1 pr\u00e9-inscrita para representar o Brasil nos Gay Games, em agosto, em Paris, no torneio de v\u00f4lei de praia. A jogadora transexual tem atuado em competi\u00e7\u00f5es femininas h\u00e1 cerca de tr\u00eas anos.<\/p>\n<p>Leia tamb\u00e9m:\u00a0<a href=\"https:\/\/blogs.correio24horas.com.br\/mesalte\/primeira-lutadora-transexual-de-mma-do-brasil-fara-sua-estreia-contra-um-homem-em-manaus\/\" target=\"_blank\">Primeira lutadora transexual de MMA do Brasil far\u00e1 sua estreia contra homem cis em Manaus<\/a><\/p>\n<p>Procurada pela GloboEsporte.com, a Confedera\u00e7\u00e3o Brasileira de V\u00f4lei afirmou que o torneio no RS n\u00e3o \u00e9 chancelado pela entidade. A Confedera\u00e7\u00e3o disse ainda que n\u00e3o foi consultada ou contactada sobre o assunto e que, se fosse, seguiria as diretrizes do Comit\u00ea Ol\u00edmpico Internacional (COI). <a href=\"https:\/\/blogs.correio24horas.com.br\/mesalte\/participacao-de-transgeneros-no-volei-cabera-as-federacoes\/\" target=\"_blank\">A atleta Carol, nesse caso, poderia jogar, como Tiffany na Superliga.<\/a><\/p>\n<p>O Sesc tamb\u00e9m foi procurado pelo GloboEsporte.com e explicou que o documento de Carol n\u00e3o foi checado devidamente pela mesa de arbitragem no ano passado e que a atleta teria jogado de forma irregular por erro da organiza\u00e7\u00e3o.\u00a0 O regulamento do campeonato n\u00e3o cita especificamente o caso de atletas transexuais e prev\u00ea apenas que sejam aceitas carteira de identidade, carteira de motorista, passaporte, carteira de trabalho com foto e cart\u00e3o do Sesc .<\/p>\n<div id=\"attachment_14664\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-14664\" class=\"size-large wp-image-14664\" src=\"https:\/\/blogs.correio24h.com.br\/mesalte\/wp-content\/uploads\/2018\/02\/top-c-1024x331.png\" alt=\"Foto: Reprodu\u00e7\u00e3o\/Globo Esporte.com\" width=\"1024\" height=\"331\" srcset=\"https:\/\/blogs.correio24h.com.br\/mesalte\/wp-content\/uploads\/2018\/02\/top-c-1024x331.png 1024w, https:\/\/blogs.correio24h.com.br\/mesalte\/wp-content\/uploads\/2018\/02\/top-c-300x97.png 300w, https:\/\/blogs.correio24h.com.br\/mesalte\/wp-content\/uploads\/2018\/02\/top-c-768x248.png 768w, https:\/\/blogs.correio24h.com.br\/mesalte\/wp-content\/uploads\/2018\/02\/top-c-260x84.png 260w, https:\/\/blogs.correio24h.com.br\/mesalte\/wp-content\/uploads\/2018\/02\/top-c-50x16.png 50w, https:\/\/blogs.correio24h.com.br\/mesalte\/wp-content\/uploads\/2018\/02\/top-c-150x48.png 150w, https:\/\/blogs.correio24h.com.br\/mesalte\/wp-content\/uploads\/2018\/02\/top-c.png 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><p id=\"caption-attachment-14664\" class=\"wp-caption-text\">Foto: Reprodu\u00e7\u00e3o\/Globo Esporte.com<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>A jogadora de v\u00f4lei de praia\u00a0Carol Lissarassa &#8211; que fez parceria com a campe\u00e3 Juliana em um torneio de v\u00f4lei de praia em novembro de 2017 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[80,11],"tags":[],"class_list":["post-14662","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-home","category-me-informo","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts\/14662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/comments?post=14662"}],"version-history":[{"count":3,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts\/14662\/revisions"}],"predecessor-version":[{"id":14667,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts\/14662\/revisions\/14667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/media\/14665"}],"wp:attachment":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/media?parent=14662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/categories?post=14662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/tags?post=14662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}