{"id":14568,"date":"2018-02-15T23:36:17","date_gmt":"2018-02-16T02:36:17","guid":{"rendered":"http:\/\/blogs.correio24horas.com.br\/mesalte\/?p=14568"},"modified":"2018-02-16T12:34:37","modified_gmt":"2018-02-16T15:34:37","slug":"grupo-rouge-anuncia-show-dia-2-de-junho-em-salvador","status":"publish","type":"post","link":"https:\/\/blogs.correio24horas.com.br\/mesalte\/grupo-rouge-anuncia-show-dia-2-de-junho-em-salvador\/","title":{"rendered":"Grupo Rouge anuncia show dia 2 de junho em Salvador"},"content":{"rendered":"<p>Segura essa Salvador! Depois do cancelamento do show no camarote Tribus no Carnaval o grupo Rouge vai fazer show em Salvador dia 2 de junho no Alto do Andu. O an\u00fancio foi feito pelo instagram oficial da banda que celebra turn\u00ea de 15 anos. As vendas come\u00e7am nesta sexta-feira ( 16) pelo<a href=\"https:\/\/www.sympla.com.br\/rouge-15-anos---salvador__241734\" target=\"_blank\"> Sympla<\/a>. Os ingressos est\u00e3o sendo vendidos a partir de R$ 50.<\/p>\n<p>Formado em 2002 no programa Popstars, transmitido pelo SBT e produzido pela companhia argentina RGB Entertainmentm, as cinco integrantes foram selecionadas dentre 30 mil candidatas. O primeiro \u00e1lbum do grupo, Rouge (2002), vendeu mais de 2 milh\u00f5es de c\u00f3pias no Brasil.<\/p>\n<p>O grupo se separou em junho de 2006, quando o contrato com a gravadora Sony Music expirou e n\u00e3o foi renovado. Em novembro de 2017, o Rouge assinou com a Sony Music Brasil pra fazer uma nova turn\u00ea com as integrantes originais: Aline Wirley, Fantine Th\u00f3, Karin Hils, Li Martins e Lu Andrade.<\/p>\n<p><strong>Vamos ensaiando o TOP 3 do grupo?\u00a0<\/strong><\/p>\n<p>1. Ragatanga<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/jSa_E00fBhg\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>2. Um Anjo veio me falar<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/ZzhHqxSdcYY\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>3. Bailando<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/jIMn66a4Ol4\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segura essa Salvador! Depois do cancelamento do show no camarote Tribus no Carnaval o grupo Rouge vai fazer show em Salvador dia 2 de junho no [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":14569,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"image","meta":{"footnotes":""},"categories":[80,16],"tags":[],"class_list":["post-14568","post","type-post","status-publish","format-image","has-post-thumbnail","hentry","category-home","category-me-jogo","post_format-post-format-image"],"_links":{"self":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts\/14568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/comments?post=14568"}],"version-history":[{"count":6,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts\/14568\/revisions"}],"predecessor-version":[{"id":14577,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/posts\/14568\/revisions\/14577"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/media\/14569"}],"wp:attachment":[{"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/media?parent=14568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/categories?post=14568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogs.correio24horas.com.br\/mesalte\/wp-json\/wp\/v2\/tags?post=14568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}